{"id":565,"count":120,"description":"<h2>National and internationals judge together<\/h2>\r\n<em>Mixed tribunals are judicial institutions that combine elements of national and international law to try the most serious crimes (war crimes, crimes against humanity, genocide, etc.). They are established by agreements between national governments and international institutions, typically the United Nations. Their aim is to ensure fair and impartial trials and to strengthen the rule of law in the concerned countries. Justice Info covers the prosecutions and trials conducted before these mixed tribunals.<\/em>","link":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals","name":"Mixed tribunals","slug":"mixed-tribunals","taxonomy":"category","parent":541,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mixed tribunals - JusticeInfo.net<\/title>\n<meta name=\"description\" content=\"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l&#039;humanit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Mixed tribunals\" \/>\n<meta property=\"og:description\" content=\"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l&#039;humanit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals\" \/>\n<meta property=\"og:site_name\" content=\"JusticeInfo.net\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@justiceinfonet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals\",\"url\":\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals\",\"name\":\"Mixed tribunals - JusticeInfo.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#website\"},\"description\":\"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l'humanit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.justiceinfo.net\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tribunals\",\"item\":\"https:\/\/www.justiceinfo.net\/en\/tribunals\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mixed tribunals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#website\",\"url\":\"https:\/\/www.justiceinfo.net\/en\/\",\"name\":\"JusticeInfo.net\",\"description\":\"For justice to be done, it must be seen\",\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.justiceinfo.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#organization\",\"name\":\"Justice Info\",\"url\":\"https:\/\/www.justiceinfo.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"contentUrl\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"width\":1199,\"height\":1200,\"caption\":\"Justice Info\"},\"image\":{\"@id\":\"https:\/\/www.justiceinfo.net\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/JusticeInfo\/\",\"https:\/\/x.com\/justiceinfonet\",\"https:\/\/www.linkedin.com\/company\/justice-info\",\"https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mixed tribunals - JusticeInfo.net","description":"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l'humanit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals","og_locale":"en_US","og_type":"article","og_title":"Archives des Mixed tribunals","og_description":"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l'humanit\u00e9.","og_url":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals","og_site_name":"JusticeInfo.net","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@justiceinfonet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals","url":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals","name":"Mixed tribunals - JusticeInfo.net","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/en\/#website"},"description":"Tous nos articles sur les tribunaux mixtes. Quand nationaux et internationaux jugent ensemble des actes de g\u00e9nocide, crimes de guerre et crimes contre l'humanit\u00e9.","breadcrumb":{"@id":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.justiceinfo.net\/en\/tribunals\/mixed-tribunals#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justiceinfo.net\/en"},{"@type":"ListItem","position":2,"name":"Tribunals","item":"https:\/\/www.justiceinfo.net\/en\/tribunals"},{"@type":"ListItem","position":3,"name":"Mixed tribunals"}]},{"@type":"WebSite","@id":"https:\/\/www.justiceinfo.net\/en\/#website","url":"https:\/\/www.justiceinfo.net\/en\/","name":"JusticeInfo.net","description":"For justice to be done, it must be seen","publisher":{"@id":"https:\/\/www.justiceinfo.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justiceinfo.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.justiceinfo.net\/en\/#organization","name":"Justice Info","url":"https:\/\/www.justiceinfo.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.justiceinfo.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","contentUrl":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","width":1199,"height":1200,"caption":"Justice Info"},"image":{"@id":"https:\/\/www.justiceinfo.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JusticeInfo\/","https:\/\/x.com\/justiceinfonet","https:\/\/www.linkedin.com\/company\/justice-info","https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA"]}]}},"_links":{"self":[{"href":"https:\/\/www.justiceinfo.net\/en\/wp-json\/wp\/v2\/categories\/565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiceinfo.net\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.justiceinfo.net\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/en\/wp-json\/wp\/v2\/categories\/541"}],"wp:post_type":[{"href":"https:\/\/www.justiceinfo.net\/en\/wp-json\/wp\/v2\/posts?categories=565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}