{"id":159105,"date":"2026-05-12T20:13:02","date_gmt":"2026-05-12T18:13:02","guid":{"rendered":"https:\/\/www.justiceinfo.net\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html"},"modified":"2026-05-12T20:13:02","modified_gmt":"2026-05-12T18:13:02","slug":"la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision","status":"publish","type":"post","link":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html","title":{"rendered":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision"},"content":{"rendered":"<p>\n             Les favoris finlandais, grec et isra\u00e9lien se sont qualifi\u00e9s sans surprise mardi, lors de la premi\u00e8re demi-finale de l'Eurovision dans une ambiance festive, malgr\u00e9 l'appel au boycott lanc\u00e9 en raison de la participation d'Isra\u00ebl.\n<\/p>\n<p>\n            La Belgique, la Su\u00e8de, la Moldavie, la Serbie, la Croatie, la Lituanie et la Pologne ont aussi obtenu leur ticket pour la finale de samedi, contrairement \u00e0 l'Estonie, la G\u00e9orgie, le Mont\u00e9n\u00e9gro, le Portugal et Saint-Marin.\n<\/p>\n<p>\n            La violoniste Linda Lampenius et le chanteur Pete Parkkonen, les candidats de la Finlande, ont enflamm\u00e9 les plus de 11.000 spectateurs rassembl\u00e9s dans la grande salle Stadthalle de Vienne avec leur duo efficace.\n<\/p>\n<p>\n            Interrog\u00e9s par l'AFP dimanche, ils n'avaient pas sembl\u00e9 stress\u00e9s par leur statut de chouchous des parieurs.\n<\/p>\n<p>\n            \"Le ressenti doit venir du coeur\", avait expliqu\u00e9 ce duo compos\u00e9 d'une violoniste de 56 ans et d'un chanteur de 36 ans qui fait mouche avec un titre, \"Liekinheitin\", \"Lance-flamme\", interpr\u00e9t\u00e9 en finnois.\n<\/p>\n<p>\n            Akylas, le candidat envoy\u00e9 par Ath\u00e8nes, a aussi conquis l'audience dans sa langue maternelle avec son morceau \u00e9lectro-pop color\u00e9 d\u00e9non\u00e7ant la cupidit\u00e9 et la qu\u00eate de richesse mat\u00e9rielle.\n<\/p>\n<p>\n            Le candidat isra\u00e9lien Noam Bettan, qui a chant\u00e9 en h\u00e9breu, fran\u00e7ais et anglais, a r\u00e9ussi \u00e0 se qualifier, \u00e0 la grande joie de ses fans.\n<\/p>\n<p>\n            La chanteuse grecque Vicki Leandros, qui avait repr\u00e9sent\u00e9 le Luxembourg \u00e0 l'Eurovision en 1967 \u00e0 Vienne avec \"L'amour est bleu\"  et en 1972 avec \"Apr\u00e8s toi\", a ouvert les festivit\u00e9s c\u00f4t\u00e9 nostalgie, alors que le concours, tr\u00e8s francophile, c\u00e9l\u00e8bre cette ann\u00e9e son 70e anniversaire.\n<\/p>\n<p>\n            Boy George, star des ann\u00e9es 1980, a fait une apparition sur la sc\u00e8ne impressionnante lors du passage de la chanteuse Senhit, qui repr\u00e9sente Saint-Marin, mais sa notori\u00e9t\u00e9 n'aura pas fait pencher la balance.\n<\/p>\n<p>\n            - \"Deux points de vue\" -\n<\/p>\n<p>\n            Le concours est \u00e9branl\u00e9 cette ann\u00e9e par le plus important boycott de son histoire.\n<\/p>\n<p>\n            Les groupes audiovisuels publics de l'Espagne, de l'Irlande et de la Slov\u00e9nie n'ont pas diffus\u00e9 le premier direct du programme, qualifi\u00e9 de \"cirque\" par le groupe slov\u00e8ne RTV.\n<\/p>\n<p>\n            Les trois pays ont d\u00e9cid\u00e9 de ne pas envoyer de candidat en raison de la pr\u00e9sence d'Isra\u00ebl, \u00e0 qui ils reprochent la conduite de la guerre \u00e0 Gaza en repr\u00e9sailles \u00e0 l'attaque le 7 octobre 2023 du mouvement islamiste palestinien Hamas sur son sol.\n<\/p>\n<p>\n            Tout comme l'Islande et les Pays-Bas, qui en revanche diffusent l'\u00e9v\u00e9nement auquel 35 pays au total prennent part.\n<\/p>\n<p>\n            Le d\u00e9put\u00e9 fran\u00e7ais Thomas Portes (gauche radicale) a \u00e9voqu\u00e9 le sujet mardi en conf\u00e9rence de presse \u00e0 l'Assembl\u00e9e nationale \u00e0 Paris.\n<\/p>\n<p>\n            \"Laisser Isra\u00ebl sur la sc\u00e8ne de l'Eurovision n'est pas neutre\", a-t-il d\u00e9clar\u00e9. \"C'est laisser faire, c'est banaliser les crimes de guerre et les crimes contre l'humanit\u00e9\".\n<\/p>\n<p>\n            Quelques dizaines de militants propalestiniens ont d\u00e9pos\u00e9 des cercueils dans le centre de la capitale autrichienne mardi pour protester contre la participation d'Isra\u00ebl.\n<\/p>\n<p>\n            \"Bien s\u00fbr, la musique devrait \u00eatre quelque chose d'universel. La musique devrait rassembler les gens, mais pas de cette mani\u00e8re\", a d\u00e9clar\u00e9 \u00e0 l'AFP Karin Spindlberger, une manifestante de 67 ans.\n<\/p>\n<p>\n            Pour Martin Green, le directeur de l'Eurovision, \"c'est tr\u00e8s sain que deux points de vue puissent s'exprimer simultan\u00e9ment dans la m\u00eame ville\".\n<\/p>\n<p>\n            \"Chacun respecte l'espace de l'autre, l'Autriche \u00e9tant un pays qui permet \u00e0 chacun d'exprimer son point de vue, et je pense qu'elle peut en \u00eatre tr\u00e8s fi\u00e8re\", a-t-il d\u00e9clar\u00e9 mardi en conf\u00e9rence de presse.\n<\/p>\n<p>\n            Amichai Chikli, le ministre isra\u00e9lien des Affaires \u00e9trang\u00e8res, s'est inqui\u00e9t\u00e9 lundi dans un communiqu\u00e9 d'une \"forte pouss\u00e9e, coordonn\u00e9e, de discours antis\u00e9mites et anti-isra\u00e9liens autour de l'Eurovision 2026\".\n<\/p>\n<p>\n            Lors de la seconde demi-finale le 14 mai, l'Albanie, le Danemark, l'Arm\u00e9nie, la Roumanie, Chypre, la Suisse, la Norv\u00e8ge, l'Azerba\u00efdjan, le Luxembourg, Malte, la Bulgarie, l'Australie, l'Ukraine, la R\u00e9publique tch\u00e8que et la Lettonie tenteront leur chance.\n<\/p>\n<p>\n            Les points des jurys sont combin\u00e9s aux r\u00e9sultats d'un vote du public, pour d\u00e9terminer les dix chansons qualifi\u00e9es lors de chaque demi-finale.\n<\/p>\n<p>\n            Ces 20 chansons rejoindront les titres pr\u00e9s\u00e9lectionn\u00e9s de l'Autriche, gagnante de l'ann\u00e9e derni\u00e8re \u00e0 B\u00e2le, en Suisse, et qualifi\u00e9e d'office pour la finale samedi.\n<\/p>\n<p>\n            La France, l'Allemagne, l'Italie et le Royaume-Uni viennent automatiquement compl\u00e9ter le tableau, en raison de leur statut de principaux contributeurs financiers.\n<\/p>\n<p>\n            bur-bg\/oaa\/lrb\/emp\/roc\n<\/p>\n<p>\n            MYTILINEOS HOLDINGS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les favoris finlandais, grec et isra\u00e9lien se sont qualifi\u00e9s sans surprise mardi, lors de la premi\u00e8re demi-finale de l'Eurovision dans une ambiance festive, malgr\u00e9 l'appel au boycott lanc\u00e9 en raison de la participation d'Isra\u00ebl. La Belgique, la Su\u00e8de, la Moldavie, la Serbie, la Croatie, la Lituanie et la Pologne ont aussi obtenu leur ticket pour [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2576],"tags":[],"ji_location":[],"class_list":["post-159105","post","type-post","status-publish","format-standard","hentry","category-fil-d-actualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l&#039;Eurovision - JusticeInfo.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l&#039;Eurovision\" \/>\n<meta property=\"og:description\" content=\"Les favoris finlandais, grec et isra\u00e9lien se sont qualifi\u00e9s sans surprise mardi, lors de la premi\u00e8re demi-finale de l&#039;Eurovision dans une ambiance festive, malgr\u00e9 l&#039;appel au boycott lanc\u00e9 en raison de la participation d&#039;Isra\u00ebl. La Belgique, la Su\u00e8de, la Moldavie, la Serbie, la Croatie, la Lituanie et la Pologne ont aussi obtenu leur ticket pour [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\" \/>\n<meta property=\"og:site_name\" content=\"JusticeInfo.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JusticeInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T18:13:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:site\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"afp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\"},\"author\":{\"name\":\"afp\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/713d340ef5f218fc36ce9b4244364a7f\"},\"headline\":\"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision\",\"datePublished\":\"2026-05-12T18:13:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"articleSection\":[\"Fil d'info AFP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\",\"name\":\"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision - JusticeInfo.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\"},\"datePublished\":\"2026-05-12T18:13:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.justiceinfo.net\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"name\":\"JusticeInfo.net\",\"description\":\"La justice doit \u00eatre vue pour \u00eatre rendue\",\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\",\"name\":\"Justice Info\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"contentUrl\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"width\":1199,\"height\":1200,\"caption\":\"Justice Info\"},\"image\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/JusticeInfo\/\",\"https:\/\/x.com\/justiceinfonet\",\"https:\/\/www.linkedin.com\/company\/justice-info\",\"https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA\"]},{\"@type\":\"Person\",\"name\":\"afp\",\"url\":\"\/fr\/?s=afp\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision - JusticeInfo.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html","og_locale":"fr_FR","og_type":"article","og_title":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision","og_description":"Les favoris finlandais, grec et isra\u00e9lien se sont qualifi\u00e9s sans surprise mardi, lors de la premi\u00e8re demi-finale de l'Eurovision dans une ambiance festive, malgr\u00e9 l'appel au boycott lanc\u00e9 en raison de la participation d'Isra\u00ebl. La Belgique, la Su\u00e8de, la Moldavie, la Serbie, la Croatie, la Lituanie et la Pologne ont aussi obtenu leur ticket pour [&hellip;]","og_url":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html","og_site_name":"JusticeInfo.net","article_publisher":"https:\/\/www.facebook.com\/JusticeInfo\/","article_published_time":"2026-05-12T18:13:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg","type":"image\/jpeg"}],"author":"afp","twitter_card":"summary_large_image","twitter_creator":"@justiceinfonet","twitter_site":"@justiceinfonet","twitter_misc":{"\u00c9crit par":"afp","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#article","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html"},"author":{"name":"afp","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/713d340ef5f218fc36ce9b4244364a7f"},"headline":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision","datePublished":"2026-05-12T18:13:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"articleSection":["Fil d'info AFP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html","url":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html","name":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision - JusticeInfo.net","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr#website"},"datePublished":"2026-05-12T18:13:02+00:00","breadcrumb":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justiceinfo.net\/fr\/159105-la-finlande-la-grece-et-israel-qualifies-lors-de-la-demi-finale-de-leurovision.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justiceinfo.net\/fr"},{"@type":"ListItem","position":2,"name":"La Finlande, la Gr\u00e8ce et Isra\u00ebl qualifi\u00e9s lors de la demi-finale de l'Eurovision"}]},{"@type":"WebSite","@id":"https:\/\/www.justiceinfo.net\/fr#website","url":"https:\/\/www.justiceinfo.net\/fr","name":"JusticeInfo.net","description":"La justice doit \u00eatre vue pour \u00eatre rendue","publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.justiceinfo.net\/fr#organization","name":"Justice Info","url":"https:\/\/www.justiceinfo.net\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","contentUrl":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","width":1199,"height":1200,"caption":"Justice Info"},"image":{"@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JusticeInfo\/","https:\/\/x.com\/justiceinfonet","https:\/\/www.linkedin.com\/company\/justice-info","https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA"]},{"@type":"Person","name":"afp","url":"\/fr\/?s=afp"}]}},"_links":{"self":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/159105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/comments?post=159105"}],"version-history":[{"count":0,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/159105\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/media?parent=159105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/categories?post=159105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/tags?post=159105"},{"taxonomy":"ji_location","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/ji_location?post=159105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}