{"id":159111,"date":"2026-05-13T02:03:02","date_gmt":"2026-05-13T00:03:02","guid":{"rendered":"https:\/\/www.justiceinfo.net\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html"},"modified":"2026-05-13T02:03:02","modified_gmt":"2026-05-13T00:03:02","slug":"pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan","status":"publish","type":"post","link":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html","title":{"rendered":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan"},"content":{"rendered":"<p>\n             Nesma* joue attendrie avec son b\u00e9b\u00e9 sur les genoux. Il a les yeux et le sourire de sa m\u00e8re mais rien de son p\u00e8re, l'un des trois combattants paramilitaires qui l'ont viol\u00e9e en r\u00e9union il y a deux ans \u00e0 Khartoum.\n<\/p>\n<p>\n            \"J'ai vu leurs visages. Je me souviens tr\u00e8s bien d'eux\", raconte cette dipl\u00f4m\u00e9e de 26 ans \u00e0 l'AFP qui a pu rencontrer plusieurs victimes de viols \u00e0 travers le Soudan en guerre.\n<\/p>\n<p>\n            Le petit Yasser est l'un des milliers d'enfants n\u00e9s de viols depuis le d\u00e9but des combats entre l'arm\u00e9e soudanaise et les paramilitaires des Forces de soutien rapide (FSR) en avril 2023.\n<\/p>\n<p>\n            Nesma avait fui la capitale soudanaise avec sa famille au d\u00e9but de la guerre. Un an apr\u00e8s, elle a d\u00fb y retourner pour r\u00e9cup\u00e9rer des documents officiels.\n<\/p>\n<p>\n            L\u00e0, au milieu des usines du nord de Khartoum, des combattants des FSR arr\u00eatent son bus, demandent aux voyageurs de descendre, s\u00e9parent les hommes des femmes.\n<\/p>\n<p>\n            Nesma subit l'assaut de trois agresseurs avant de perdre connaissance. \"Je suis revenue \u00e0 moi le lendemain matin. L'un des passagers du bus gisait \u00e0 terre, abattu d'une balle.\"\n<\/p>\n<p>\n            Son r\u00e9cit correspond au mode op\u00e9ratoire des combattants des FSR qui, selon des experts de l'ONU, ont men\u00e9 des violences sexuelles syst\u00e9matiques au Soudan.\n<\/p>\n<p>\n            Le traumatisme a \u00e9t\u00e9 tel pour la jeune femme qu'elle n'a r\u00e9alis\u00e9 sa grossesse qu'au bout de cinq mois. Jusqu'\u00e0 la veille de sa c\u00e9sarienne, elle n'\u00e9tait pas s\u00fbre de garder le b\u00e9b\u00e9.\n<\/p>\n<p>\n            \"Et puis, je n'ai pas pu le laisser partir\", confie-t-elle, disant \"ne pas avoir support\u00e9 l'id\u00e9e qu'il souffre ou tombe dans une mauvaise famille\", tandis que Yasser se niche dans son cou.\n<\/p>\n<p>\n            \"Ce n'est pas la faute de mon fils, tout comme ce n'est pas la mienne.\"\n<\/p>\n<p>\n            - Silence et honte -\n<\/p>\n<p>\n            La ministre soudanaise aux Affaires sociales, Souleima Ishaq al-Khalifa, estime \u00e0 plusieurs milliers le nombre de victimes de viols au Soudan. Mais la grande majorit\u00e9 gardent le silence et il n'y a pas non plus trace administrative de nombreux avortements ou adoptions souvent informelles, souligne-t-elle.\n<\/p>\n<p>\n            Au Darfour, dans une seule ville, \"des centaines et des centaines de cas de jeune filles viol\u00e9es ont \u00e9t\u00e9 recens\u00e9s. La plupart sont tomb\u00e9es enceintes et aucune n'est all\u00e9e consulter\", rapporte \u00e0 l'AFP la coordinatrice de l'ONU au Soudan Denise Brown.\n<\/p>\n<p>\n            A Tawila, ville de l'\u00c9tat du Darfour du Nord qui abrite des centaines de milliers de d\u00e9plac\u00e9s, Gloria Endreo, une sage-femme de M\u00e9decins sans fronti\u00e8res (MSF), a vu en deux mois des centaines de survivantes dont beaucoup enceintes \u00e0 la suite d'un viol. \"Certaines n'arrivaient m\u00eame pas \u00e0 le dire\", raconte-t-elle \u00e0 l'AFP.\n<\/p>\n<p>\n            La honte que beaucoup ressentent dans ce pays conservateur fait que la plupart de ces enfants sont \u00e9lev\u00e9s en secret. Des victimes peuvent \u00eatre rejet\u00e9es voire accus\u00e9es d'avoir pactis\u00e9 avec les FSR.\n<\/p>\n<p>\n            \"Des familles ont abandonn\u00e9 leurs filles, des maris ont divorc\u00e9 de leur femme viol\u00e9e\", elles sont victimes d'une double injustice, d\u00e9plore Reem Alsalem, rapporteuse sp\u00e9ciale de l'ONU sur la violence contre les femmes et les jeunes filles.\n<\/p>\n<p>\n            Dans ce conflit, le viol est utilis\u00e9 comme une arme \"de guerre, de domination, de destruction et de g\u00e9nocide pour d\u00e9truire le tissu social et en changer sa composition\", analyse-t-elle.\n<\/p>\n<p>\n            Les viols de masse faisaient d\u00e9j\u00e0 partie des crimes contre l'humanit\u00e9 imput\u00e9s aux Janjawids, milices arabes dont sont issues les FSR, au d\u00e9but des ann\u00e9es 2000.\n<\/p>\n<p>\n            - Trois fois -\n<\/p>\n<p>\n            Dans un abri de paille \u00e0 Tawila, Hayat, 20 ans, tente d'endormir son fils de quatre mois. Elle esp\u00e8re pour lui \"un avenir meilleur\": \"Je ne veux pas qu'il grandisse comme nous\", souffle-t-elle.\n<\/p>\n<p>\n            Hayat a \u00e9t\u00e9 viol\u00e9e alors qu'elle fuyait le camp de Zamzam, pr\u00e8s d'El-Facher, derni\u00e8re grande ville du Darfour du Nord tomb\u00e9e aux mains des FSR en octobre 2025.\n<\/p>\n<p>\n            Lors de leur attaque contre ce site, qui abritait un demi-million de personnes, les paramilitaires sont accus\u00e9s d'avoir tu\u00e9 plus de 1.000 civils et men\u00e9 une campagne de viols syst\u00e9matiques visant les femmes de groupes ethniques non-arabes, selon l'ONU.\n<\/p>\n<p>\n            Halima, 23 ans, a v\u00e9cu ce calvaire trois fois, viol\u00e9e adolescente par des gardiens de troupeaux quand elle travaillait dans les champs, puis en 2022 sur la route de Zamzam et enfin lorsqu'elle s'est \u00e9chapp\u00e9e de ce camp.\n<\/p>\n<p>\n            La jeune femme \u00e9l\u00e8ve ses deux enfants n\u00e9s des premiers viols mais a \u00e9vit\u00e9 une troisi\u00e8me grossesse gr\u00e2ce \u00e0 une contraception d'urgence prescrite par des m\u00e9decins.\n<\/p>\n<p>\n            A Tawila, l'AFP a rencontr\u00e9 plusieurs survivantes viol\u00e9es et tomb\u00e9es enceintes au moment de la chute d'El-Facher, au cours de laquelle les paramilitaires ont tu\u00e9 au moins 6.000 personnes en trois jours.\n<\/p>\n<p>\n            Comme Rawia, 17 ans. Elle a vu les FSR tuer la moiti\u00e9 des personnes avec qui elle prenait la fuite. Puis \"trois d'entre eux nous ont d\u00e9pouill\u00e9es de toutes nos affaires et nous ont viol\u00e9es\". Elle est enceinte de cinq mois.\n<\/p>\n<p>\n            Alia, 25 ans, a \u00e9t\u00e9 ramen\u00e9e de force \u00e0 El-Facher avec quatre autres jeunes filles, retenues captives pendant six semaines, \"jusqu'\u00e0 ce que nous nous enfuyions au milieu de la nuit\". Elle fait alors une fausse-couche.\n<\/p>\n<p>\n            Magda, 22 ans, a perdu son mari dans une attaque \u00e0 la roquette puis a vu son fr\u00e8re se faire abattre sur la route de Tawila. Elle a \u00e9t\u00e9 viol\u00e9e il y a cinq mois.\n<\/p>\n<p>\n            \"Quand j'ai appris que j'\u00e9tais enceinte, je me suis dit: +Si je perds ce b\u00e9b\u00e9, ce sera une personne de plus \u00e0 pleurer. Mais s'il vit, c'est le destin, je l'\u00e9l\u00e8verai+.\"\n<\/p>\n<p>\n            - \"Instinct maternel\" -\n<\/p>\n<p>\n            Fayha*, elle, a \u00e9t\u00e9 viol\u00e9e par un civil pendant qu'un de ses amis, un soldat alors en repos mais arm\u00e9, montait la garde.\n<\/p>\n<p>\n            \"J'\u00e9tais terroris\u00e9e \u00e0 l'id\u00e9e qu'il me tire dessus\", se rem\u00e9more-telle, les larmes aux yeux, ber\u00e7ant son b\u00e9b\u00e9 de cinq mois dans la chaleur accablante de Khartoum.\n<\/p>\n<p>\n            Selon l'ONU, les violences sexuelles commises par l'arm\u00e9e sont largement sous-d\u00e9clar\u00e9es par peur des repr\u00e9sailles. Les observateurs estiment n\u00e9anmoins qu'elles ne sont pas comparables avec la strat\u00e9gie syst\u00e9matique de viols mise en oeuvre par les paramilitaires.\n<\/p>\n<p>\n            \"Les FSR violent pour soumettre la soci\u00e9t\u00e9, d\u00e9placer et dominer ; les soldats de l'arm\u00e9e violent parce qu'ils savent qu'ils resteront impunis\", explique \u00e0 l'AFP une militante sous couvert d'anonymat.\n<\/p>\n<p>\n            Fayha n'a r\u00e9alis\u00e9 qu'elle \u00e9tait enceinte qu'apr\u00e8s son premier trimestre de grossesse. A 30 ans, elle d\u00e9couvre la maternit\u00e9 dans ces conditions o\u00f9 elle doit \"\u00eatre \u00e0 la fois m\u00e8re et p\u00e8re\".\n<\/p>\n<p>\n            \"Parfois je m'\u00e9nerve, c'est l'heure de le nourrir et j'en ai assez de lui\". Mais \"r\u00e9cemment, j'ai commenc\u00e9 \u00e0 ressentir un peu plus d'instinct maternel\", confie-t-elle.\n<\/p>\n<p>\n            Pour certaines qui ont accouch\u00e9 malgr\u00e9 elles, il est difficile de \"manifester de l'amour ou de l'attention vis-\u00e0-vis d'un enfant qu'elles sont ensuite forc\u00e9es d'\u00e9lever alors qu'il leur rappelle constamment ce qu'elles ont v\u00e9cu\", t\u00e9moigne Gloria Endreo de MSF.\n<\/p>\n<p>\n            Fayha, comme Nesma et tant d'autres ont d\u00fb en plus se battre pour obtenir l'acte de naissance, sans lequel ces petits ne pourront b\u00e9n\u00e9ficier de soins, d'aide ou d'\u00e9ducation.\n<\/p>\n<p>\n            Normalement \"cela ne devrait pas poser probl\u00e8me, des proc\u00e9dures existent\", assure Souleima Ishaq al-Khalifa, qui a milit\u00e9 pour la cause des femmes avant d'entrer au gouvernement.\n<\/p>\n<p>\n            Dans les faits, les normes sociales conservatrices et l'effondrement de l'administration du pays compliquent les choses.\n<\/p>\n<p>\n            \"Quel va \u00eatre le statut l\u00e9gal de ces enfants ?\" s'inqui\u00e8te Denise Brown, qui voit l\u00e0 un \"probl\u00e8me sur le long terme\". \"Comment seront-ils pris en charge au sein des familles ? Quelles cons\u00e9quences cela aura-t-il sur les communaut\u00e9s ?\"\n<\/p>\n<p>\n            - Un \"b\u00e9b\u00e9 FSR\" -\n<\/p>\n<p>\n            Dans l'\u00c9tat d'al-Jazirah, au sud-est de Khartoum, les traumatismes sont particuli\u00e8rement \u00e0 vif.\n<\/p>\n<p>\n            Lors des raids des paramilitaires, des jeunes filles \u00e0 la peau plus claire, issues de groupes ethniques diff\u00e9rents de ceux des combattants des FSR, ont \u00e9t\u00e9 \"explicitement cibl\u00e9es et trait\u00e9es comme des butins de guerre\", selon l'organisation de d\u00e9fense des droits des femmes Siha.\n<\/p>\n<p>\n            De nombreuses familles ont quitt\u00e9 d\u00e9finitivement leur village pour \u00e9chapper au traumatisme des viols collectifs, des mariages forc\u00e9s, de l'esclavage sexuel inflig\u00e9s par les FSR.\n<\/p>\n<p>\n            Quand l'arm\u00e9e a repris le centre du Soudan en 2025, le gouvernement a assoupli les r\u00e8gles sur l'avortement dans une tentative d'att\u00e9nuer l'impact sur la soci\u00e9t\u00e9 des violences sexuelles commises par les FSR.\n<\/p>\n<p>\n            \"Il y a eu une certaine tol\u00e9rance en mati\u00e8re d'avortement mais beaucoup l'ignoraient et il fallait obtenir une autorisation. Et \u00e0 cause de la honte sociale, beaucoup ne se sont pas signal\u00e9es\", rel\u00e8ve la rapporteuse sp\u00e9ciale de l'ONU, Reem Alsalem.\n<\/p>\n<p>\n            Une b\u00e9n\u00e9vole a confi\u00e9 \u00e0 l'AFP avoir aid\u00e9 26 femmes et jeunes filles \u00e0 avorter. La plupart \"avaient pris avant des m\u00e9dicaments extr\u00eamement dangereux\".\n<\/p>\n<p>\n            A Tawila, Gloria Endreo de MSF \u00e9voque ces femmes recueillies qui \"saignaient apr\u00e8s avoir tent\u00e9 des avortements clandestins\".\n<\/p>\n<p>\n            La ministre aux Affaires sociales se souvient aussi de cette adolescente de 16 ans, oblig\u00e9e d'aller au bout de sa grossesse : \u00e0 peine avait-elle accouch\u00e9 que la grand-m\u00e8re \"a pris l'enfant dans ses bras, nous l'a tendu et a dit: +Nous ne ram\u00e8nerons pas ce b\u00e9b\u00e9 des FSR \u00e0 la maison+\".\n<\/p>\n<p>\n            \"Elle voulait que tout cela soit effac\u00e9, comme si rien ne s'\u00e9tait jamais pass\u00e9\", poursuit Mme Khalifa. Le b\u00e9b\u00e9 a \u00e9t\u00e9 confi\u00e9 \u00e0 une famille d'accueil.\n<\/p>\n<p>\n            - \"Il m\u00e9rite une belle vie\" -\n<\/p>\n<p>\n            D'autres victimes ont \u00e9t\u00e9 mari\u00e9es de force \u00e0 des paramilitaires et emmen\u00e9es avec eux au Darfour lorsqu'ils s'y sont repli\u00e9s. Leur famille n'ont pas pu payer la ran\u00e7on pour les lib\u00e9rer.\n<\/p>\n<p>\n            A Nyala, capitale du Darfour du Sud, \"il y a des dizaines de filles et de femmes dont les enfants ont maintenant un ou deux ans et elles sont pi\u00e9g\u00e9es\", selon la ministre.\n<\/p>\n<p>\n            Et puis il y a celles qui ont profit\u00e9 des d\u00e9placements massifs de population - 11 millions de d\u00e9plac\u00e9s selon l'ONU dans cette guerre - pour \u00e9lever leur enfant sans que personne ne connaisse les conditions de sa conception.\n<\/p>\n<p>\n            \"Beaucoup n'avaient plus les m\u00eames voisins, elles ont pu accoucher sans que cela se sache et faire passer le b\u00e9b\u00e9 pour un fr\u00e8re ou une soeur ou pour un enfant victime de la guerre qu'elles auraient recueilli\", raconte la ministre.\n<\/p>\n<p>\n            Le gouvernement tente de placer le plus grand nombre possible d'enfants abandonn\u00e9s mais beaucoup sont adopt\u00e9s de mani\u00e8re informelle, en particulier dans l'est du Soudan o\u00f9 l'accueil de petits dans le besoin est une pratique \u00e9tablie. Mme Alsalem s'inqui\u00e8te d'ailleurs du \"peu de suivi et de contr\u00f4le\".\n<\/p>\n<p>\n            Depuis qu'elle a accouch\u00e9, m\u00eame en pleine d\u00e9pression, Nesma n'a jamais envisag\u00e9 se s\u00e9parer de Yasser.\n<\/p>\n<p>\n            Aujourd'hui, son fils a treize mois. Elle a deux objectifs: s'occuper de lui le mieux possible et d\u00e9crocher un emploi bien pay\u00e9 gr\u00e2ce \u00e0 son dipl\u00f4me universitaire.\n<\/p>\n<p>\n            \"Il m\u00e9rite une belle vie\", murmure-t-elle, tenant ses menottes pour l'accompagner dans ses premiers pas.\n<\/p>\n<p>\n            * pr\u00e9noms modifi\u00e9s \u00e0 la demande des victimes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesma* joue attendrie avec son b\u00e9b\u00e9 sur les genoux. Il a les yeux et le sourire de sa m\u00e8re mais rien de son p\u00e8re, l'un des trois combattants paramilitaires qui l'ont viol\u00e9e en r\u00e9union il y a deux ans \u00e0 Khartoum. \"J'ai vu leurs visages. Je me souviens tr\u00e8s bien d'eux\", raconte cette dipl\u00f4m\u00e9e de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2576],"tags":[],"ji_location":[],"class_list":["post-159111","post","type-post","status-publish","format-standard","hentry","category-fil-d-actualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Pas sa faute&quot; : ces m\u00e8res d&#039;enfants n\u00e9s des viols de la guerre au Soudan - JusticeInfo.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Pas sa faute&quot; : ces m\u00e8res d&#039;enfants n\u00e9s des viols de la guerre au Soudan\" \/>\n<meta property=\"og:description\" content=\"Nesma* joue attendrie avec son b\u00e9b\u00e9 sur les genoux. Il a les yeux et le sourire de sa m\u00e8re mais rien de son p\u00e8re, l&#039;un des trois combattants paramilitaires qui l&#039;ont viol\u00e9e en r\u00e9union il y a deux ans \u00e0 Khartoum. &quot;J&#039;ai vu leurs visages. Je me souviens tr\u00e8s bien d&#039;eux&quot;, raconte cette dipl\u00f4m\u00e9e de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\" \/>\n<meta property=\"og:site_name\" content=\"JusticeInfo.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JusticeInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T00:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"afp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:site\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"afp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\"},\"author\":{\"name\":\"afp\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/713d340ef5f218fc36ce9b4244364a7f\"},\"headline\":\"\\\"Pas sa faute\\\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan\",\"datePublished\":\"2026-05-13T00:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\"},\"wordCount\":2018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"articleSection\":[\"Fil d'info AFP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\",\"name\":\"\\\"Pas sa faute\\\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan - JusticeInfo.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\"},\"datePublished\":\"2026-05-13T00:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.justiceinfo.net\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\\"Pas sa faute\\\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"name\":\"JusticeInfo.net\",\"description\":\"La justice doit \u00eatre vue pour \u00eatre rendue\",\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\",\"name\":\"Justice Info\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"contentUrl\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"width\":1199,\"height\":1200,\"caption\":\"Justice Info\"},\"image\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/JusticeInfo\/\",\"https:\/\/x.com\/justiceinfonet\",\"https:\/\/www.linkedin.com\/company\/justice-info\",\"https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA\"]},{\"@type\":\"Person\",\"name\":\"afp\",\"url\":\"\/fr\/?s=afp\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan - JusticeInfo.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html","og_locale":"fr_FR","og_type":"article","og_title":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan","og_description":"Nesma* joue attendrie avec son b\u00e9b\u00e9 sur les genoux. Il a les yeux et le sourire de sa m\u00e8re mais rien de son p\u00e8re, l'un des trois combattants paramilitaires qui l'ont viol\u00e9e en r\u00e9union il y a deux ans \u00e0 Khartoum. \"J'ai vu leurs visages. Je me souviens tr\u00e8s bien d'eux\", raconte cette dipl\u00f4m\u00e9e de [&hellip;]","og_url":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html","og_site_name":"JusticeInfo.net","article_publisher":"https:\/\/www.facebook.com\/JusticeInfo\/","article_published_time":"2026-05-13T00:03:02+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg","type":"image\/jpeg"}],"author":"afp","twitter_card":"summary_large_image","twitter_creator":"@justiceinfonet","twitter_site":"@justiceinfonet","twitter_misc":{"\u00c9crit par":"afp","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#article","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html"},"author":{"name":"afp","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/713d340ef5f218fc36ce9b4244364a7f"},"headline":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan","datePublished":"2026-05-13T00:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html"},"wordCount":2018,"commentCount":0,"publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"articleSection":["Fil d'info AFP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html","url":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html","name":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan - JusticeInfo.net","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr#website"},"datePublished":"2026-05-13T00:03:02+00:00","breadcrumb":{"@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justiceinfo.net\/fr\/159111-pas-sa-faute-ces-meres-denfants-nes-des-viols-de-la-guerre-au-soudan.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justiceinfo.net\/fr"},{"@type":"ListItem","position":2,"name":"\"Pas sa faute\" : ces m\u00e8res d'enfants n\u00e9s des viols de la guerre au Soudan"}]},{"@type":"WebSite","@id":"https:\/\/www.justiceinfo.net\/fr#website","url":"https:\/\/www.justiceinfo.net\/fr","name":"JusticeInfo.net","description":"La justice doit \u00eatre vue pour \u00eatre rendue","publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.justiceinfo.net\/fr#organization","name":"Justice Info","url":"https:\/\/www.justiceinfo.net\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","contentUrl":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","width":1199,"height":1200,"caption":"Justice Info"},"image":{"@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JusticeInfo\/","https:\/\/x.com\/justiceinfonet","https:\/\/www.linkedin.com\/company\/justice-info","https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA"]},{"@type":"Person","name":"afp","url":"\/fr\/?s=afp"}]}},"_links":{"self":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/159111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/comments?post=159111"}],"version-history":[{"count":0,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/159111\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/media?parent=159111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/categories?post=159111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/tags?post=159111"},{"taxonomy":"ji_location","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/ji_location?post=159111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}