{"id":8046,"date":"2007-07-10T00:00:00","date_gmt":"2007-07-09T22:00:00","guid":{"rendered":"https:\/\/www.justiceinfo.net\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html"},"modified":"2007-07-10T00:00:00","modified_gmt":"2007-07-09T22:00:00","slug":"100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846","status":"publish","type":"post","link":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html","title":{"rendered":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)"},"content":{"rendered":"<p>Arusha, 10 juillet 2007 (FH)-L&rsquo;ex-maire Joseph Kanyabashi &eacute;tait &laquo; impuissant &raquo; pendant le g&eacute;nocide des Tutsis dont il est accus&eacute; devant le Tribunal p&eacute;nal &nbsp;international pour le Rwanda (TPIR), a plaid&eacute; mardi son avocat.&nbsp;&nbsp;<br \/>\n<!--more-->&laquo;Kanyabashi &eacute;tait impuissant &raquo;, a d&eacute;clar&eacute; l&rsquo;avocat canadien Me Michel Marchand en introduisant les t&eacute;moins &agrave; d&eacute;charge qui compara&icirc;tront en ao&ucirc;t. &nbsp; Kanyabashi, 70 ans, &eacute;tait maire de Ngoma &agrave; Butare dans le sud du Rwanda en 1994. Il est accus&eacute; de massacres dans sa commune. Il plaide non coupable. &nbsp; &nbsp; &laquo; Quel pouvoir avait le bourgmestre (maire) Kanyabashi qui n&rsquo;a m&ecirc;me pas pu emp&ecirc;cher la mort de ses proches ? D&rsquo;autres autorit&eacute;s ont pu prot&eacute;ger des amis ou des proches de l&rsquo;ethnie tutsie &raquo;, a fait remarquer Me Marchand. &nbsp; Le d&eacute;fenseur a nomm&eacute; les membres de la belle-famille de l&rsquo;accus&eacute; qui ont &eacute;t&eacute; tu&eacute;s &agrave; l&rsquo;&eacute;glise de Ngoma ainsi que dans la commune voisine de Huye par des militaires accompagn&eacute;s de civils. &nbsp; Selon Me Marchand, le maire Kanyabashi &laquo; n&rsquo;&eacute;tait plus qu&rsquo;un figurant &raquo; face aux toutes puissantes &laquo; forces g&eacute;nocidaires &raquo;. &nbsp; &laquo; Comment Monsieur Kanyabashi d&eacute;j&agrave; qualifi&eacute;, avant 94, de Kanyabatutsi (ami des Tutsis) pouvait-il emp&ecirc;cher les militaires, qui avaient d&eacute;cid&eacute; de se mettre au service du g&eacute;nocide, de massacrer les Tutsis qui avaient trouv&eacute; refuge en commune Ngoma. &raquo;, s&rsquo;est interrog&eacute;e sa d&eacute;fense. &laquo; Ayant &eacute;t&eacute; un bourgmestre aim&eacute; de sa population durant vingt ans, il est normal que celle-ci le croyait capable d&rsquo;enrayer le g&eacute;nocide &raquo;, a poursuivi l&rsquo;avocat. &nbsp; &laquo; Malheureusement, ce dont il &eacute;tait capable en temps normal fut r&eacute;duit &agrave; z&eacute;ro &agrave; compter du moment o&ugrave; les forces g&eacute;nocidaires ont d&eacute;cid&eacute; de mater la ville de Butare qui avait jusque l&agrave; r&eacute;sist&eacute; tant bien que mal &agrave; la folie meurtri&egrave;re qui avait d&eacute;j&agrave; atteint plusieurs pr&eacute;fectures et m&ecirc;me certaines parties de la pr&eacute;fecture de Butare,&raquo; a-t-il expliqu&eacute;. &nbsp; &nbsp;Me Marchand a indiqu&eacute; que Kanyabashi &laquo; est profond&eacute;ment marqu&eacute; &raquo; par le g&eacute;nocide commis sur des milliers de ses administr&eacute;s tutsis et la mort de Hutus oppos&eacute;s &agrave; ce g&eacute;nocide. &nbsp; L&rsquo;accus&eacute; entend &nbsp;d&eacute;montrer &laquo; qu&rsquo;il n&rsquo;a pas ordonn&eacute; ni particip&eacute; aux atrocit&eacute;s commises dans sa commune entre avril et juillet 1994 &raquo;. &nbsp; La chambre a ordonn&eacute; que Kanyabashi pr&eacute;sente trente t&eacute;moins. Il a fait appel et demand&eacute; l&rsquo;ajout d&rsquo;au moins quinze autres. La d&eacute;cision est encore attendue. &nbsp; Kanyabashi &laquo; esp&egrave;re que les survivants pourront comprendre le cauchemar qu&rsquo;il a v&eacute;cu et son incapacit&eacute; d&rsquo;emp&ecirc;cher les forces du mal. Il a fait ce qu&rsquo;il a pu dans les circonstances pour tenter d&rsquo;emp&ecirc;cher les tueries et sauver des gens &raquo;, a soulign&eacute; sa d&eacute;fense. Arr&ecirc;t&eacute; le 28 juin 1995 en Belgique, Kanyabashi est jug&eacute; depuis le 12 juin 2001 avec cinq autres personnalit&eacute;s originaires de Butare. Il sera le cinqui&egrave;me accus&eacute; dans ce proc&egrave;s dit du groupe &laquo; Butare &raquo; &agrave; pr&eacute;senter sa d&eacute;fense. Apr&egrave;s la d&eacute;claration liminaire de Me Marchand, les d&eacute;bats ont &eacute;t&eacute; ajourn&eacute;s jusqu&rsquo;au 20 ao&ucirc;t. AT\/GF &copy; Agence Hirondelle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arusha, 10 juillet 2007 (FH)-L&rsquo;ex-maire Joseph Kanyabashi &eacute;tait &laquo; impuissant &raquo; pendant le g&eacute;nocide des Tutsis dont il est accus&eacute; devant le Tribunal p&eacute;nal &nbsp;international pour le Rwanda (TPIR), a plaid&eacute; mardi son avocat.&nbsp;&nbsp;<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[554],"tags":[],"ji_location":[],"class_list":["post-8046","post","type-post","status-publish","format-standard","hentry","category-hirondellenews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.3.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE) - JusticeInfo.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)\" \/>\n<meta property=\"og:description\" content=\"Arusha, 10 juillet 2007 (FH)-L&rsquo;ex-maire Joseph Kanyabashi &eacute;tait &laquo; impuissant &raquo; pendant le g&eacute;nocide des Tutsis dont il est accus&eacute; devant le Tribunal p&eacute;nal &nbsp;international pour le Rwanda (TPIR), a plaid&eacute; mardi son avocat.&nbsp;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\" \/>\n<meta property=\"og:site_name\" content=\"JusticeInfo.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JusticeInfo\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-09T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"solivri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:site\" content=\"@justiceinfonet\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"solivri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\"},\"author\":{\"name\":\"solivri\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/6e53cba1629e2e66f3fc1821d3091865\"},\"headline\":\"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)\",\"datePublished\":\"2007-07-09T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\"},\"wordCount\":708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"articleSection\":[\"Hirondelle News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\",\"name\":\"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE) - JusticeInfo.net\",\"isPartOf\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\"},\"datePublished\":\"2007-07-09T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.justiceinfo.net\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#website\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"name\":\"JusticeInfo.net\",\"description\":\"La justice doit \u00eatre vue pour \u00eatre rendue\",\"publisher\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#organization\",\"name\":\"Justice Info\",\"url\":\"https:\/\/www.justiceinfo.net\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"contentUrl\":\"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png\",\"width\":1199,\"height\":1200,\"caption\":\"Justice Info\"},\"image\":{\"@id\":\"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/JusticeInfo\/\",\"https:\/\/x.com\/justiceinfonet\",\"https:\/\/www.linkedin.com\/company\/justice-info\",\"https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA\"]},{\"@type\":\"Person\",\"name\":\"solivri\",\"url\":\"\/fr\/?s=solivri\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE) - JusticeInfo.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html","og_locale":"fr_FR","og_type":"article","og_title":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)","og_description":"Arusha, 10 juillet 2007 (FH)-L&rsquo;ex-maire Joseph Kanyabashi &eacute;tait &laquo; impuissant &raquo; pendant le g&eacute;nocide des Tutsis dont il est accus&eacute; devant le Tribunal p&eacute;nal &nbsp;international pour le Rwanda (TPIR), a plaid&eacute; mardi son avocat.&nbsp;&nbsp;","og_url":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html","og_site_name":"JusticeInfo.net","article_publisher":"https:\/\/www.facebook.com\/JusticeInfo\/","article_published_time":"2007-07-09T22:00:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/JusticeInfoNet_logo_1200x630px.jpg","type":"image\/jpeg"}],"author":"solivri","twitter_card":"summary_large_image","twitter_creator":"@justiceinfonet","twitter_site":"@justiceinfonet","twitter_misc":{"\u00c9crit par":"solivri","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#article","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html"},"author":{"name":"solivri","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/person\/6e53cba1629e2e66f3fc1821d3091865"},"headline":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)","datePublished":"2007-07-09T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html"},"wordCount":708,"commentCount":0,"publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"articleSection":["Hirondelle News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html","url":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html","name":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE) - JusticeInfo.net","isPartOf":{"@id":"https:\/\/www.justiceinfo.net\/fr#website"},"datePublished":"2007-07-09T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.justiceinfo.net\/fr\/8046-100707-tpirbutare-lex-maire-kanyabashi-impuissant-pendant-le-genocide-defense4846.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.justiceinfo.net\/fr"},{"@type":"ListItem","position":2,"name":"10.07.07 - TPIR\/BUTARE - L\u2019EX-MAIRE KANYABASHI IMPUISSANT PENDANT LE GENOCIDE (DEFENSE)"}]},{"@type":"WebSite","@id":"https:\/\/www.justiceinfo.net\/fr#website","url":"https:\/\/www.justiceinfo.net\/fr","name":"JusticeInfo.net","description":"La justice doit \u00eatre vue pour \u00eatre rendue","publisher":{"@id":"https:\/\/www.justiceinfo.net\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.justiceinfo.net\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.justiceinfo.net\/fr#organization","name":"Justice Info","url":"https:\/\/www.justiceinfo.net\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/","url":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","contentUrl":"https:\/\/www.justiceinfo.net\/wp-content\/uploads\/justiceinfo_logo-trans_1200x1200px.png","width":1199,"height":1200,"caption":"Justice Info"},"image":{"@id":"https:\/\/www.justiceinfo.net\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JusticeInfo\/","https:\/\/x.com\/justiceinfonet","https:\/\/www.linkedin.com\/company\/justice-info","https:\/\/www.youtube.com\/channel\/UCyCEsARodyuWtkWyhn-e7pA"]},{"@type":"Person","name":"solivri","url":"\/fr\/?s=solivri"}]}},"_links":{"self":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/8046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/comments?post=8046"}],"version-history":[{"count":0,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/posts\/8046\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/media?parent=8046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/categories?post=8046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/tags?post=8046"},{"taxonomy":"ji_location","embeddable":true,"href":"https:\/\/www.justiceinfo.net\/fr\/wp-json\/wp\/v2\/ji_location?post=8046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}